{"id":4180,"date":"2020-10-02T05:15:58","date_gmt":"2020-10-02T05:15:58","guid":{"rendered":"https:\/\/altairasesores.es\/?p=4180"},"modified":"2023-07-06T06:05:23","modified_gmt":"2023-07-06T06:05:23","slug":"asistencia-tecnica-para-la-evaluacion-de-las-convocatorias-de-propuestas-en-virtud-del-ipa-ii","status":"publish","type":"post","link":"https:\/\/altairasesores.es\/es\/asistencia-tecnica-para-la-evaluacion-de-las-convocatorias-de-propuestas-en-virtud-del-ipa-ii\/","title":{"rendered":"Asistencia T\u00e9cnica Para La Evaluaci\u00f3n De Las Convocatorias De Propuestas En Virtud del IPA II."},"content":{"rendered":"<p>\u00c1rea geogr\u00e1fica: Macedonia del Norte<br \/>\nA\u00f1o: 2020<\/p>\n<p>La Comisi\u00f3n Europea ha otorgado a Altair la asistencia t\u00e9cnica para la evaluaci\u00f3n de las convocatorias de propuestas en virtud del IPA II. El objetivo general del proyecto es ayudar a la Autoridad Contratante al seleccionar los proyectos de la mejor calidad bajo una serie de solicitudes de propuestas. El prop\u00f3sito de este contrato es proporcionar experiencia t\u00e9cnica independiente como un asesor (miembro que no votante) para aumentar la eficiencia en la evaluaci\u00f3n de las propuestas de proyectos en una serie de convocatorias de propuestas, de acuerdo con las reglas de &#8220;adquisiciones y subvenciones para la Uni\u00f3n Europea externa. comportamiento&#8217;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c1rea geogr\u00e1fica: Macedonia del Norte A\u00f1o: 2020 La Comisi\u00f3n Europea ha otorgado a Altair la asistencia t\u00e9cnica para la evaluaci\u00f3n de las convocatorias de propuestas en virtud del IPA II. El objetivo general del proyecto es ayudar a la Autoridad Contratante al seleccionar los proyectos de la mejor calidad bajo una serie de solicitudes de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4144,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"nf_dc_page":"","site-sidebar-layout":"default","site-content-layout":"default","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[180],"tags":[],"class_list":["post-4180","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Asistencia T\u00e9cnica Para La Evaluaci\u00f3n De Las Convocatorias De Propuestas En Virtud del IPA II. - Altair Asesores<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/altairasesores.es\/es\/asistencia-tecnica-para-la-evaluacion-de-las-convocatorias-de-propuestas-en-virtud-del-ipa-ii\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Asistencia T\u00e9cnica Para La Evaluaci\u00f3n De Las Convocatorias De Propuestas En Virtud del IPA II. - Altair Asesores\" \/>\n<meta property=\"og:description\" content=\"\u00c1rea geogr\u00e1fica: Macedonia del Norte A\u00f1o: 2020 La Comisi\u00f3n Europea ha otorgado a Altair la asistencia t\u00e9cnica para la evaluaci\u00f3n de las convocatorias de propuestas en virtud del IPA II. El objetivo general del proyecto es ayudar a la Autoridad Contratante al seleccionar los proyectos de la mejor calidad bajo una serie de solicitudes de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/altairasesores.es\/es\/asistencia-tecnica-para-la-evaluacion-de-las-convocatorias-de-propuestas-en-virtud-del-ipa-ii\/\" \/>\n<meta property=\"og:site_name\" content=\"Altair Asesores\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-02T05:15:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-06T06:05:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/altairasesores.es\/wp-content\/uploads\/2023\/07\/maced.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"734\" \/>\n\t<meta property=\"og:image:height\" content=\"493\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"kodrant\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"kodrant\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/altairasesores.es\\\/es\\\/asistencia-tecnica-para-la-evaluacion-de-las-convocatorias-de-propuestas-en-virtud-del-ipa-ii\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/altairasesores.es\\\/es\\\/asistencia-tecnica-para-la-evaluacion-de-las-convocatorias-de-propuestas-en-virtud-del-ipa-ii\\\/\"},\"author\":{\"name\":\"kodrant\",\"@id\":\"https:\\\/\\\/altairasesores.es\\\/es\\\/#\\\/schema\\\/person\\\/90fbcc58cfc5774e4a41cc2b158383ee\"},\"headline\":\"Asistencia T\u00e9cnica Para La Evaluaci\u00f3n De Las Convocatorias De Propuestas En Virtud del IPA II.\",\"datePublished\":\"2020-10-02T05:15:58+00:00\",\"dateModified\":\"2023-07-06T06:05:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/altairasesores.es\\\/es\\\/asistencia-tecnica-para-la-evaluacion-de-las-convocatorias-de-propuestas-en-virtud-del-ipa-ii\\\/\"},\"wordCount\":132,\"publisher\":{\"@id\":\"https:\\\/\\\/altairasesores.es\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/altairasesores.es\\\/es\\\/asistencia-tecnica-para-la-evaluacion-de-las-convocatorias-de-propuestas-en-virtud-del-ipa-ii\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/altairasesores.es\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/maced.jpg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/altairasesores.es\\\/es\\\/asistencia-tecnica-para-la-evaluacion-de-las-convocatorias-de-propuestas-en-virtud-del-ipa-ii\\\/\",\"url\":\"https:\\\/\\\/altairasesores.es\\\/es\\\/asistencia-tecnica-para-la-evaluacion-de-las-convocatorias-de-propuestas-en-virtud-del-ipa-ii\\\/\",\"name\":\"Asistencia T\u00e9cnica Para La Evaluaci\u00f3n De Las Convocatorias De Propuestas En Virtud del IPA II. - Altair Asesores\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/altairasesores.es\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/altairasesores.es\\\/es\\\/asistencia-tecnica-para-la-evaluacion-de-las-convocatorias-de-propuestas-en-virtud-del-ipa-ii\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/altairasesores.es\\\/es\\\/asistencia-tecnica-para-la-evaluacion-de-las-convocatorias-de-propuestas-en-virtud-del-ipa-ii\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/altairasesores.es\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/maced.jpg\",\"datePublished\":\"2020-10-02T05:15:58+00:00\",\"dateModified\":\"2023-07-06T06:05:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/altairasesores.es\\\/es\\\/asistencia-tecnica-para-la-evaluacion-de-las-convocatorias-de-propuestas-en-virtud-del-ipa-ii\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/altairasesores.es\\\/es\\\/asistencia-tecnica-para-la-evaluacion-de-las-convocatorias-de-propuestas-en-virtud-del-ipa-ii\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/altairasesores.es\\\/es\\\/asistencia-tecnica-para-la-evaluacion-de-las-convocatorias-de-propuestas-en-virtud-del-ipa-ii\\\/#primaryimage\",\"url\":\"https:\\\/\\\/altairasesores.es\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/maced.jpg\",\"contentUrl\":\"https:\\\/\\\/altairasesores.es\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/maced.jpg\",\"width\":734,\"height\":493},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/altairasesores.es\\\/es\\\/asistencia-tecnica-para-la-evaluacion-de-las-convocatorias-de-propuestas-en-virtud-del-ipa-ii\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/altairasesores.es\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Asistencia T\u00e9cnica Para La Evaluaci\u00f3n De Las Convocatorias De Propuestas En Virtud del IPA II.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/altairasesores.es\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/altairasesores.es\\\/es\\\/\",\"name\":\"Altair Asesores\",\"description\":\"Creating better world, promoting good governance and development\",\"publisher\":{\"@id\":\"https:\\\/\\\/altairasesores.es\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/altairasesores.es\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/altairasesores.es\\\/es\\\/#organization\",\"name\":\"Altair Asesores\",\"url\":\"https:\\\/\\\/altairasesores.es\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/altairasesores.es\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/altairasesores.es\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/cropped-altairlogo.png\",\"contentUrl\":\"https:\\\/\\\/altairasesores.es\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/cropped-altairlogo.png\",\"width\":406,\"height\":162,\"caption\":\"Altair Asesores\"},\"image\":{\"@id\":\"https:\\\/\\\/altairasesores.es\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/altairasesores.es\\\/es\\\/#\\\/schema\\\/person\\\/90fbcc58cfc5774e4a41cc2b158383ee\",\"name\":\"kodrant\",\"sameAs\":[\"https:\\\/\\\/altairasesores.es\"],\"url\":\"https:\\\/\\\/altairasesores.es\\\/es\\\/author\\\/kodrant\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Asistencia T\u00e9cnica Para La Evaluaci\u00f3n De Las Convocatorias De Propuestas En Virtud del IPA II. - Altair Asesores","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/altairasesores.es\/es\/asistencia-tecnica-para-la-evaluacion-de-las-convocatorias-de-propuestas-en-virtud-del-ipa-ii\/","og_locale":"es_ES","og_type":"article","og_title":"Asistencia T\u00e9cnica Para La Evaluaci\u00f3n De Las Convocatorias De Propuestas En Virtud del IPA II. - Altair Asesores","og_description":"\u00c1rea geogr\u00e1fica: Macedonia del Norte A\u00f1o: 2020 La Comisi\u00f3n Europea ha otorgado a Altair la asistencia t\u00e9cnica para la evaluaci\u00f3n de las convocatorias de propuestas en virtud del IPA II. El objetivo general del proyecto es ayudar a la Autoridad Contratante al seleccionar los proyectos de la mejor calidad bajo una serie de solicitudes de [&hellip;]","og_url":"https:\/\/altairasesores.es\/es\/asistencia-tecnica-para-la-evaluacion-de-las-convocatorias-de-propuestas-en-virtud-del-ipa-ii\/","og_site_name":"Altair Asesores","article_published_time":"2020-10-02T05:15:58+00:00","article_modified_time":"2023-07-06T06:05:23+00:00","og_image":[{"width":734,"height":493,"url":"https:\/\/altairasesores.es\/wp-content\/uploads\/2023\/07\/maced.jpg","type":"image\/jpeg"}],"author":"kodrant","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"kodrant","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/altairasesores.es\/es\/asistencia-tecnica-para-la-evaluacion-de-las-convocatorias-de-propuestas-en-virtud-del-ipa-ii\/#article","isPartOf":{"@id":"https:\/\/altairasesores.es\/es\/asistencia-tecnica-para-la-evaluacion-de-las-convocatorias-de-propuestas-en-virtud-del-ipa-ii\/"},"author":{"name":"kodrant","@id":"https:\/\/altairasesores.es\/es\/#\/schema\/person\/90fbcc58cfc5774e4a41cc2b158383ee"},"headline":"Asistencia T\u00e9cnica Para La Evaluaci\u00f3n De Las Convocatorias De Propuestas En Virtud del IPA II.","datePublished":"2020-10-02T05:15:58+00:00","dateModified":"2023-07-06T06:05:23+00:00","mainEntityOfPage":{"@id":"https:\/\/altairasesores.es\/es\/asistencia-tecnica-para-la-evaluacion-de-las-convocatorias-de-propuestas-en-virtud-del-ipa-ii\/"},"wordCount":132,"publisher":{"@id":"https:\/\/altairasesores.es\/es\/#organization"},"image":{"@id":"https:\/\/altairasesores.es\/es\/asistencia-tecnica-para-la-evaluacion-de-las-convocatorias-de-propuestas-en-virtud-del-ipa-ii\/#primaryimage"},"thumbnailUrl":"https:\/\/altairasesores.es\/wp-content\/uploads\/2023\/07\/maced.jpg","articleSection":["Noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/altairasesores.es\/es\/asistencia-tecnica-para-la-evaluacion-de-las-convocatorias-de-propuestas-en-virtud-del-ipa-ii\/","url":"https:\/\/altairasesores.es\/es\/asistencia-tecnica-para-la-evaluacion-de-las-convocatorias-de-propuestas-en-virtud-del-ipa-ii\/","name":"Asistencia T\u00e9cnica Para La Evaluaci\u00f3n De Las Convocatorias De Propuestas En Virtud del IPA II. - Altair Asesores","isPartOf":{"@id":"https:\/\/altairasesores.es\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/altairasesores.es\/es\/asistencia-tecnica-para-la-evaluacion-de-las-convocatorias-de-propuestas-en-virtud-del-ipa-ii\/#primaryimage"},"image":{"@id":"https:\/\/altairasesores.es\/es\/asistencia-tecnica-para-la-evaluacion-de-las-convocatorias-de-propuestas-en-virtud-del-ipa-ii\/#primaryimage"},"thumbnailUrl":"https:\/\/altairasesores.es\/wp-content\/uploads\/2023\/07\/maced.jpg","datePublished":"2020-10-02T05:15:58+00:00","dateModified":"2023-07-06T06:05:23+00:00","breadcrumb":{"@id":"https:\/\/altairasesores.es\/es\/asistencia-tecnica-para-la-evaluacion-de-las-convocatorias-de-propuestas-en-virtud-del-ipa-ii\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/altairasesores.es\/es\/asistencia-tecnica-para-la-evaluacion-de-las-convocatorias-de-propuestas-en-virtud-del-ipa-ii\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/altairasesores.es\/es\/asistencia-tecnica-para-la-evaluacion-de-las-convocatorias-de-propuestas-en-virtud-del-ipa-ii\/#primaryimage","url":"https:\/\/altairasesores.es\/wp-content\/uploads\/2023\/07\/maced.jpg","contentUrl":"https:\/\/altairasesores.es\/wp-content\/uploads\/2023\/07\/maced.jpg","width":734,"height":493},{"@type":"BreadcrumbList","@id":"https:\/\/altairasesores.es\/es\/asistencia-tecnica-para-la-evaluacion-de-las-convocatorias-de-propuestas-en-virtud-del-ipa-ii\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/altairasesores.es\/es\/"},{"@type":"ListItem","position":2,"name":"Asistencia T\u00e9cnica Para La Evaluaci\u00f3n De Las Convocatorias De Propuestas En Virtud del IPA II."}]},{"@type":"WebSite","@id":"https:\/\/altairasesores.es\/es\/#website","url":"https:\/\/altairasesores.es\/es\/","name":"Altair Asesores","description":"Creating better world, promoting good governance and development","publisher":{"@id":"https:\/\/altairasesores.es\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/altairasesores.es\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/altairasesores.es\/es\/#organization","name":"Altair Asesores","url":"https:\/\/altairasesores.es\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/altairasesores.es\/es\/#\/schema\/logo\/image\/","url":"https:\/\/altairasesores.es\/wp-content\/uploads\/2022\/10\/cropped-altairlogo.png","contentUrl":"https:\/\/altairasesores.es\/wp-content\/uploads\/2022\/10\/cropped-altairlogo.png","width":406,"height":162,"caption":"Altair Asesores"},"image":{"@id":"https:\/\/altairasesores.es\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/altairasesores.es\/es\/#\/schema\/person\/90fbcc58cfc5774e4a41cc2b158383ee","name":"kodrant","sameAs":["https:\/\/altairasesores.es"],"url":"https:\/\/altairasesores.es\/es\/author\/kodrant\/"}]}},"_links":{"self":[{"href":"https:\/\/altairasesores.es\/es\/wp-json\/wp\/v2\/posts\/4180","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/altairasesores.es\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/altairasesores.es\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/altairasesores.es\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/altairasesores.es\/es\/wp-json\/wp\/v2\/comments?post=4180"}],"version-history":[{"count":1,"href":"https:\/\/altairasesores.es\/es\/wp-json\/wp\/v2\/posts\/4180\/revisions"}],"predecessor-version":[{"id":4181,"href":"https:\/\/altairasesores.es\/es\/wp-json\/wp\/v2\/posts\/4180\/revisions\/4181"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/altairasesores.es\/es\/wp-json\/wp\/v2\/media\/4144"}],"wp:attachment":[{"href":"https:\/\/altairasesores.es\/es\/wp-json\/wp\/v2\/media?parent=4180"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/altairasesores.es\/es\/wp-json\/wp\/v2\/categories?post=4180"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/altairasesores.es\/es\/wp-json\/wp\/v2\/tags?post=4180"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}