{"id":252,"date":"2021-08-22T12:24:54","date_gmt":"2021-08-22T12:24:54","guid":{"rendered":"https:\/\/altairasesores.es\/?p=252"},"modified":"2023-01-07T11:50:27","modified_gmt":"2023-01-07T11:50:27","slug":"evaluacion-final-del-fortalecimiento-de-los-procesos-de-reconciliacion","status":"publish","type":"post","link":"https:\/\/altairasesores.es\/es\/evaluacion-final-del-fortalecimiento-de-los-procesos-de-reconciliacion\/","title":{"rendered":"Evaluaci\u00f3n Final del Fortalecimiento de los Procesos de Reconciliaci\u00f3n"},"content":{"rendered":"<p>\u00c1rea Geogr\u00e1fica: Sri Lanka<\/p>\n<p>A\u00f1o: 2021<\/p>\n<p>La Comisi\u00f3n Europea ha otorgado a Altair la evaluaci\u00f3n final de Fortalecimiento de los procesos de reconciliaci\u00f3n en Sri Lanka. El objetivo general es hacer avanzar el proceso de reconciliaci\u00f3n de Sri Lanka. El objetivo espec\u00edfico es: Las organizaciones gubernamentales, no gubernamentales y de base emprenden acciones, de manera conjunta e individual, para abordar elementos clave del proceso de reconciliaci\u00f3n a trav\u00e9s de mecanismos efectivos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c1rea Geogr\u00e1fica: Sri Lanka A\u00f1o: 2021 La Comisi\u00f3n Europea ha otorgado a Altair la evaluaci\u00f3n final de Fortalecimiento de los procesos de reconciliaci\u00f3n en Sri Lanka. El objetivo general es hacer avanzar el proceso de reconciliaci\u00f3n de Sri Lanka. El objetivo espec\u00edfico es: Las organizaciones gubernamentales, no gubernamentales y de base emprenden acciones, de manera [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":250,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"nf_dc_page":"","site-sidebar-layout":"default","site-content-layout":"default","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[180],"tags":[],"class_list":["post-252","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Evaluaci\u00f3n Final del Fortalecimiento de los Procesos de Reconciliaci\u00f3n - Altair Asesores<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/altairasesores.es\/es\/evaluacion-final-del-fortalecimiento-de-los-procesos-de-reconciliacion\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Evaluaci\u00f3n Final del Fortalecimiento de los Procesos de Reconciliaci\u00f3n - Altair Asesores\" \/>\n<meta property=\"og:description\" content=\"\u00c1rea Geogr\u00e1fica: Sri Lanka A\u00f1o: 2021 La Comisi\u00f3n Europea ha otorgado a Altair la evaluaci\u00f3n final de Fortalecimiento de los procesos de reconciliaci\u00f3n en Sri Lanka. El objetivo general es hacer avanzar el proceso de reconciliaci\u00f3n de Sri Lanka. El objetivo espec\u00edfico es: Las organizaciones gubernamentales, no gubernamentales y de base emprenden acciones, de manera [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/altairasesores.es\/es\/evaluacion-final-del-fortalecimiento-de-los-procesos-de-reconciliacion\/\" \/>\n<meta property=\"og:site_name\" content=\"Altair Asesores\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-22T12:24:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-07T11:50:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/altairasesores.es\/wp-content\/uploads\/2022\/11\/srilanka-flag.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"kodrant\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"kodrant\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/altairasesores.es\\\/es\\\/evaluacion-final-del-fortalecimiento-de-los-procesos-de-reconciliacion\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/altairasesores.es\\\/es\\\/evaluacion-final-del-fortalecimiento-de-los-procesos-de-reconciliacion\\\/\"},\"author\":{\"name\":\"kodrant\",\"@id\":\"https:\\\/\\\/altairasesores.es\\\/es\\\/#\\\/schema\\\/person\\\/90fbcc58cfc5774e4a41cc2b158383ee\"},\"headline\":\"Evaluaci\u00f3n Final del Fortalecimiento de los Procesos de Reconciliaci\u00f3n\",\"datePublished\":\"2021-08-22T12:24:54+00:00\",\"dateModified\":\"2023-01-07T11:50:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/altairasesores.es\\\/es\\\/evaluacion-final-del-fortalecimiento-de-los-procesos-de-reconciliacion\\\/\"},\"wordCount\":90,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/altairasesores.es\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/altairasesores.es\\\/es\\\/evaluacion-final-del-fortalecimiento-de-los-procesos-de-reconciliacion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/altairasesores.es\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/srilanka-flag.jpeg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/altairasesores.es\\\/es\\\/evaluacion-final-del-fortalecimiento-de-los-procesos-de-reconciliacion\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/altairasesores.es\\\/es\\\/evaluacion-final-del-fortalecimiento-de-los-procesos-de-reconciliacion\\\/\",\"url\":\"https:\\\/\\\/altairasesores.es\\\/es\\\/evaluacion-final-del-fortalecimiento-de-los-procesos-de-reconciliacion\\\/\",\"name\":\"Evaluaci\u00f3n Final del Fortalecimiento de los Procesos de Reconciliaci\u00f3n - Altair Asesores\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/altairasesores.es\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/altairasesores.es\\\/es\\\/evaluacion-final-del-fortalecimiento-de-los-procesos-de-reconciliacion\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/altairasesores.es\\\/es\\\/evaluacion-final-del-fortalecimiento-de-los-procesos-de-reconciliacion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/altairasesores.es\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/srilanka-flag.jpeg\",\"datePublished\":\"2021-08-22T12:24:54+00:00\",\"dateModified\":\"2023-01-07T11:50:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/altairasesores.es\\\/es\\\/evaluacion-final-del-fortalecimiento-de-los-procesos-de-reconciliacion\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/altairasesores.es\\\/es\\\/evaluacion-final-del-fortalecimiento-de-los-procesos-de-reconciliacion\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/altairasesores.es\\\/es\\\/evaluacion-final-del-fortalecimiento-de-los-procesos-de-reconciliacion\\\/#primaryimage\",\"url\":\"https:\\\/\\\/altairasesores.es\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/srilanka-flag.jpeg\",\"contentUrl\":\"https:\\\/\\\/altairasesores.es\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/srilanka-flag.jpeg\",\"width\":800,\"height\":500,\"caption\":\"sl\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/altairasesores.es\\\/es\\\/evaluacion-final-del-fortalecimiento-de-los-procesos-de-reconciliacion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/altairasesores.es\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Evaluaci\u00f3n Final del Fortalecimiento de los Procesos de Reconciliaci\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/altairasesores.es\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/altairasesores.es\\\/es\\\/\",\"name\":\"Altair Asesores\",\"description\":\"Creating better world, promoting good governance and development\",\"publisher\":{\"@id\":\"https:\\\/\\\/altairasesores.es\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/altairasesores.es\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/altairasesores.es\\\/es\\\/#organization\",\"name\":\"Altair Asesores\",\"url\":\"https:\\\/\\\/altairasesores.es\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/altairasesores.es\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/altairasesores.es\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/cropped-altairlogo.png\",\"contentUrl\":\"https:\\\/\\\/altairasesores.es\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/cropped-altairlogo.png\",\"width\":406,\"height\":162,\"caption\":\"Altair Asesores\"},\"image\":{\"@id\":\"https:\\\/\\\/altairasesores.es\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/altairasesores.es\\\/es\\\/#\\\/schema\\\/person\\\/90fbcc58cfc5774e4a41cc2b158383ee\",\"name\":\"kodrant\",\"sameAs\":[\"https:\\\/\\\/altairasesores.es\"],\"url\":\"https:\\\/\\\/altairasesores.es\\\/es\\\/author\\\/kodrant\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Evaluaci\u00f3n Final del Fortalecimiento de los Procesos de Reconciliaci\u00f3n - Altair Asesores","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/altairasesores.es\/es\/evaluacion-final-del-fortalecimiento-de-los-procesos-de-reconciliacion\/","og_locale":"es_ES","og_type":"article","og_title":"Evaluaci\u00f3n Final del Fortalecimiento de los Procesos de Reconciliaci\u00f3n - Altair Asesores","og_description":"\u00c1rea Geogr\u00e1fica: Sri Lanka A\u00f1o: 2021 La Comisi\u00f3n Europea ha otorgado a Altair la evaluaci\u00f3n final de Fortalecimiento de los procesos de reconciliaci\u00f3n en Sri Lanka. El objetivo general es hacer avanzar el proceso de reconciliaci\u00f3n de Sri Lanka. El objetivo espec\u00edfico es: Las organizaciones gubernamentales, no gubernamentales y de base emprenden acciones, de manera [&hellip;]","og_url":"https:\/\/altairasesores.es\/es\/evaluacion-final-del-fortalecimiento-de-los-procesos-de-reconciliacion\/","og_site_name":"Altair Asesores","article_published_time":"2021-08-22T12:24:54+00:00","article_modified_time":"2023-01-07T11:50:27+00:00","og_image":[{"width":800,"height":500,"url":"https:\/\/altairasesores.es\/wp-content\/uploads\/2022\/11\/srilanka-flag.jpeg","type":"image\/jpeg"}],"author":"kodrant","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"kodrant","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/altairasesores.es\/es\/evaluacion-final-del-fortalecimiento-de-los-procesos-de-reconciliacion\/#article","isPartOf":{"@id":"https:\/\/altairasesores.es\/es\/evaluacion-final-del-fortalecimiento-de-los-procesos-de-reconciliacion\/"},"author":{"name":"kodrant","@id":"https:\/\/altairasesores.es\/es\/#\/schema\/person\/90fbcc58cfc5774e4a41cc2b158383ee"},"headline":"Evaluaci\u00f3n Final del Fortalecimiento de los Procesos de Reconciliaci\u00f3n","datePublished":"2021-08-22T12:24:54+00:00","dateModified":"2023-01-07T11:50:27+00:00","mainEntityOfPage":{"@id":"https:\/\/altairasesores.es\/es\/evaluacion-final-del-fortalecimiento-de-los-procesos-de-reconciliacion\/"},"wordCount":90,"commentCount":0,"publisher":{"@id":"https:\/\/altairasesores.es\/es\/#organization"},"image":{"@id":"https:\/\/altairasesores.es\/es\/evaluacion-final-del-fortalecimiento-de-los-procesos-de-reconciliacion\/#primaryimage"},"thumbnailUrl":"https:\/\/altairasesores.es\/wp-content\/uploads\/2022\/11\/srilanka-flag.jpeg","articleSection":["Noticias"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/altairasesores.es\/es\/evaluacion-final-del-fortalecimiento-de-los-procesos-de-reconciliacion\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/altairasesores.es\/es\/evaluacion-final-del-fortalecimiento-de-los-procesos-de-reconciliacion\/","url":"https:\/\/altairasesores.es\/es\/evaluacion-final-del-fortalecimiento-de-los-procesos-de-reconciliacion\/","name":"Evaluaci\u00f3n Final del Fortalecimiento de los Procesos de Reconciliaci\u00f3n - Altair Asesores","isPartOf":{"@id":"https:\/\/altairasesores.es\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/altairasesores.es\/es\/evaluacion-final-del-fortalecimiento-de-los-procesos-de-reconciliacion\/#primaryimage"},"image":{"@id":"https:\/\/altairasesores.es\/es\/evaluacion-final-del-fortalecimiento-de-los-procesos-de-reconciliacion\/#primaryimage"},"thumbnailUrl":"https:\/\/altairasesores.es\/wp-content\/uploads\/2022\/11\/srilanka-flag.jpeg","datePublished":"2021-08-22T12:24:54+00:00","dateModified":"2023-01-07T11:50:27+00:00","breadcrumb":{"@id":"https:\/\/altairasesores.es\/es\/evaluacion-final-del-fortalecimiento-de-los-procesos-de-reconciliacion\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/altairasesores.es\/es\/evaluacion-final-del-fortalecimiento-de-los-procesos-de-reconciliacion\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/altairasesores.es\/es\/evaluacion-final-del-fortalecimiento-de-los-procesos-de-reconciliacion\/#primaryimage","url":"https:\/\/altairasesores.es\/wp-content\/uploads\/2022\/11\/srilanka-flag.jpeg","contentUrl":"https:\/\/altairasesores.es\/wp-content\/uploads\/2022\/11\/srilanka-flag.jpeg","width":800,"height":500,"caption":"sl"},{"@type":"BreadcrumbList","@id":"https:\/\/altairasesores.es\/es\/evaluacion-final-del-fortalecimiento-de-los-procesos-de-reconciliacion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/altairasesores.es\/es\/"},{"@type":"ListItem","position":2,"name":"Evaluaci\u00f3n Final del Fortalecimiento de los Procesos de Reconciliaci\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/altairasesores.es\/es\/#website","url":"https:\/\/altairasesores.es\/es\/","name":"Altair Asesores","description":"Creating better world, promoting good governance and development","publisher":{"@id":"https:\/\/altairasesores.es\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/altairasesores.es\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/altairasesores.es\/es\/#organization","name":"Altair Asesores","url":"https:\/\/altairasesores.es\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/altairasesores.es\/es\/#\/schema\/logo\/image\/","url":"https:\/\/altairasesores.es\/wp-content\/uploads\/2022\/10\/cropped-altairlogo.png","contentUrl":"https:\/\/altairasesores.es\/wp-content\/uploads\/2022\/10\/cropped-altairlogo.png","width":406,"height":162,"caption":"Altair Asesores"},"image":{"@id":"https:\/\/altairasesores.es\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/altairasesores.es\/es\/#\/schema\/person\/90fbcc58cfc5774e4a41cc2b158383ee","name":"kodrant","sameAs":["https:\/\/altairasesores.es"],"url":"https:\/\/altairasesores.es\/es\/author\/kodrant\/"}]}},"_links":{"self":[{"href":"https:\/\/altairasesores.es\/es\/wp-json\/wp\/v2\/posts\/252","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/altairasesores.es\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/altairasesores.es\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/altairasesores.es\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/altairasesores.es\/es\/wp-json\/wp\/v2\/comments?post=252"}],"version-history":[{"count":1,"href":"https:\/\/altairasesores.es\/es\/wp-json\/wp\/v2\/posts\/252\/revisions"}],"predecessor-version":[{"id":253,"href":"https:\/\/altairasesores.es\/es\/wp-json\/wp\/v2\/posts\/252\/revisions\/253"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/altairasesores.es\/es\/wp-json\/wp\/v2\/media\/250"}],"wp:attachment":[{"href":"https:\/\/altairasesores.es\/es\/wp-json\/wp\/v2\/media?parent=252"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/altairasesores.es\/es\/wp-json\/wp\/v2\/categories?post=252"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/altairasesores.es\/es\/wp-json\/wp\/v2\/tags?post=252"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}